{"id":2603,"date":"2013-11-11T00:00:00","date_gmt":"1970-01-01T00:00:00","guid":{"rendered":"http:\/\/lireouimaisquoi.over-blog.com\/article-herland-121072658-comments.html"},"modified":"2014-08-27T23:18:58","modified_gmt":"2014-08-27T22:18:58","slug":"herland","status":"publish","type":"post","link":"http:\/\/chezyueyin.org\/blog\/herland\/","title":{"rendered":"Herland"},"content":{"rendered":"<p style=\"text-align: justify;\"> <img decoding=\"async\" src=\"https:\/\/encrypted-tbn1.gstatic.com\/images?q=tbn:ANd9GcSBCtUU8NDGLWjvWr7KWddg6hxT-nOw_hckmP9SxnUxpC7IQCJOBg\" class=\"alignleft\" height= \"227\" width=\"150\"\/> <\/p>\n<p style=\"text-align: justify;\"> <span><span>Au tout d\u00e9but du XXe si\u00e8cle, un trio de jeunes am\u00e9ricains aventureux se lancent \u00e0 la recherche d&#8217;un myst\u00e9rieux pays peupl\u00e9s uniquement de femmes. Chacun port\u00e9 par ses fantasmes, ils ont imagin\u00e9 toutes les formes que pourraient prendre une telle soci\u00e9t\u00e9, domination des hommes, sexes s\u00e9par\u00e9s voire mensonges institutionnels etc. la v\u00e9rit\u00e9 se r\u00e9v\u00e9lera totalement inattendue et changera \u00e0 jamais leur vision du monde.<\/span><\/span> <\/p>\n<p style=\"text-align: justify;\"> <span><span>Herland est une utopie aux sens premiers du mot : une soci\u00e9t\u00e9 id\u00e9ale situ\u00e9e nulle part. Concr\u00e8tement, Gilman empreinte son cadre aux romans d&#8217;aventure en vogue \u00e0 son \u00e9poque &#8211; tels ceux de <a target=\"_blank\" href=\"http:\/\/chezyueyin.org\/?p=1290\">Henri Ridder Haggard<\/a> ou Edgar Rice Burrough, et campe une vall\u00e9e perdue, s\u00e9par\u00e9e du reste du monde par une infranchissable barri\u00e8re montagneuse o\u00f9 &#8211; fantasme supr\u00eame &#8211; ne vivent que des femmes. Seulement loin de chercher \u00e0 enrichir la litt\u00e9rature de genre d&#8217;une nouvelle variation autour d&#8217;aventures exotico-fantastiques teint\u00e9es d&#8217;\u00e9rotisme colonial, l&#8217;auteure utilise cet artifice pour camper sa soci\u00e9t\u00e9 id\u00e9ale. Un monde lib\u00e9r\u00e9 des guerres et des maladies, de la pauvret\u00e9 et de la peur, vu \u00e0 travers les yeux de trois jeunes hommes &#8211; aussi \u00e9trangers que des martiens &#8211; totalement d\u00e9sorient\u00e9s par les &#8220;femmes&#8221; si peu f\u00e9minines qui les accueillent plut\u00f4t aimablement apr\u00e8s une r\u00e9ception \u00e0 la fois muscl\u00e9e et non violente.<\/span><\/span> <\/p>\n<p style=\"text-align: justify;\"> <span><span>Charlotte Perkins Gilman est c\u00e9l\u00e8bre pour son f\u00e9minisme mais si la condition des femmes est au centre du roman &#8211; Van le narrateur se rendant peu \u00e0 peu compte que ce qui lui semblait tout naturel dans la condition f\u00e9minine n&#8217;\u00e9tait qu&#8217;une construction culturelle inf\u00e9r\u00e9e par les hommes, elle aborde bien d&#8217;autres th\u00e8mes. La soci\u00e9t\u00e9 qu&#8217;elle d\u00e9crit est \u00e0 la fois progressiste, non violente, socialiste et \u00e9galitaire. Ni classe, ni hi\u00e9rarchie, ni honneur, ni argent&#8230; chacune travaille \u00e0 l&#8217;oeuvre commune avec toujours en perspective l&#8217;id\u00e9e d&#8217;am\u00e9liorer l&#8217;efficacit\u00e9 et l&#8217;esth\u00e9tique d&#8217;un \u00e9l\u00e9ment de la soci\u00e9t\u00e9. La communaut\u00e9 et la coop\u00e9ration sont constamment oppos\u00e9es aux valeurs des hommes et notamment \u00e0 celles de Terry &#8211; arch\u00e9type du m\u00e2le occidental &#8211; l\u2019individualisme et la comp\u00e9tition, amenant cens\u00e9ment le lecteur &#8211; \u00e0 travers les na\u00efves questions des herlandiennes &#8211; \u00e0 se poser de s\u00e9rieuse question sur le bien fond\u00e9e des dites valeurs. Plus int\u00e9ressant encore, Gilman aiguillonne vertement traditions et religion, y opposant une vision enti\u00e8rement fond\u00e9e sur le rationalisme et l&#8217;efficacit\u00e9 &#8211; pourquoi demande l&#8217;une des protagonistes continuer \u00e0 r\u00e9v\u00e9rer des id\u00e9es du pass\u00e9 quand nos connaissances ont tant \u00e9volu\u00e9 ? Une vraie remise en question du christianisme &#8211; si masculin &#8211; que je n&#8217;attendais gu\u00e8re dans un roman de&nbsp; cette p\u00e9riode.<\/span><\/span> <\/p>\n<p style=\"text-align: justify;\"> <span><span>Alors certes l&#8217;oeuvre reste marqu\u00e9e par son \u00e9poque et Gilman c\u00e8de un peu aux pr\u00e9jug\u00e9s de son \u00e9poque &#8211; tant qu&#8217;ils ne concernent pas les femmes &#8211; l&#8217;eug\u00e9nisme et la conception de l&#8217;h\u00e9r\u00e9dit\u00e9 d\u00e9mangent un tantinet mais peu importe. Tel quel c&#8217;est un \u00e9tonnant monument au f\u00e9minisme, peut-\u00eatre un peu \u00e9touffant cent ans plus tard &#8211; \u00e0 Herland absolument tout doit&nbsp; \u00eatre utile,&nbsp; les arbres ont donc tous \u00e9t\u00e9 remplac\u00e9s par des fruitiers, les animaux inutiles &#8211; les chiens &#8211; ont disparus et bien d&#8217;autres traits &#8211; mais bourr\u00e9es d&#8217;id\u00e9es \u00e9tonnamment modernes dont certaines suscitent toujours autant d&#8217;int\u00e9r\u00eat. J&#8217;ajouterai quand m\u00eame que la solution au probl\u00e8me purement sexuel de l&#8217;introduction de trois hommes dans un tel monde, illustre cruellement l&#8217;opinion que pouvait avoir une femme disons m\u00fbre &#8211; Charlotte \u00e9tait d\u00e9j\u00e0 divorc\u00e9e et remari\u00e9e quand elle a \u00e9crit ce roman &#8211; des &#8220;relations intimes&#8221; entre \u00e9poux. Edifiant !<br \/><\/span><\/span> <\/p>\n<p style=\"text-align: justify;\"> <span><em><span>Herland &#8211; Charlotte Perkins Gilman &#8211; 1915<\/span><\/em><\/span> <\/p>\n<p style=\"text-align: justify;\"> <span><span><em>PS<\/em> : Je ne vous ai \u00e9videmment pas r\u00e9v\u00e9l\u00e9 comment une telle soci\u00e9t\u00e9 uniquement compos\u00e9e d&#8217;\u00eatre humains de sexe f\u00e9minins a pu perdurer&#8230; Vous aurez la surprise (quoique ce ne soit \u00e9videmment pas l&#8217;essentiel du roman).<\/span><\/span> <\/p>\n<p style=\"text-align: justify;\"> <span><span><em>PPS<\/em> : Charlotte Perkins Gilman, c\u00e9l\u00e8bre \u00e0 son \u00e9poque, a eu un certain impact sur la litt\u00e9rature avec un renouveau dans les ann\u00e9es soixante-dix quand son oeuvre a \u00e9t\u00e9 exhum\u00e9e des tiroirs o\u00f9 elle prenait la poussi\u00e8re. Elle a notamment \u00e9crit, \u00e0 partir de sa propre exp\u00e9rience, ce qui doit \u00eatre la premi\u00e8re histoire d&#8217;une d\u00e9pression postpartum : the yellow wallpaper. Margaret Atwood et Ursula Le Guin seraient ses admiratrices proclam\u00e9es&#8230;<\/span><\/span> <\/p>\n<p style=\"text-align: justify;\"> <span><span><em>PPS<\/em> : Herland n&#8217;a malheureusement pas \u00e9t\u00e9 traduit \u00e0 ma connaissance mais il est dans le domaine public et vous pouvez sans probl\u00e8me le trouver sur le net.<\/span><\/span> <\/p>\n<p style=\"text-align: justify;\"> <span><span>Bien que ce ne soit d\u00e9finitivement pas un roman d&#8217;anticipation, je l&#8217;ai lu dans le cadre du challenge Anticipation de <a target=\"_blank\" href=\"http:\/\/liresouslemagnolia.unblog.fr\/\">Julie des magnolias<\/a> avec qui j&#8217;ai partag\u00e9 cette lecture et il rentre \u00e9galement dans le <a target=\"_blank\" href= \"http:\/\/22h05ruedesdames.wordpress.com\/2013\/07\/01\/le-challenge-americain\/\">mois am\u00e9ricain de noctenbule<\/a> &#8211; coup double quoi \ud83d\ude42<br \/><\/span><\/span> <\/p>\n<p style=\"text-align: justify;\"> <img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/chezyueyin.org\/blog\/wp-content\/uploads\/2013\/11\/1391689_10151942442708330_147050978_n.jpg\" height=\"173\" width=\"267\"\/><img src= \"http:\/\/chezyueyin.org\/blog\/wp-content\/uploads\/2013\/10\/challengeus11.jpg?w=392&amp;h=221\" height=\"158\" width=\"282\"> <\/p>\n<style type=\"text\/css\"> <!-- P { margin-bottom: 0.21cm; } --> <\/style>\n","protected":false},"excerpt":{"rendered":"<p>Au tout d\u00e9but du XXe si\u00e8cle, un trio de jeunes am\u00e9ricains aventureux se lancent \u00e0 la recherche d&#8217;un myst\u00e9rieux pays peupl\u00e9s uniquement de femmes. Chacun port\u00e9 par ses fantasmes, ils ont imagin\u00e9 toutes les formes que pourraient prendre une telle &hellip; <a href=\"http:\/\/chezyueyin.org\/blog\/herland\/\">Continuer la lecture <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_s2mail":"","footnotes":""},"categories":[24],"tags":[],"class_list":["post-2603","post","type-post","status-publish","format-standard","hentry","category-romanamricain"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v14.4.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<meta name=\"robots\" content=\"index, follow\" \/>\n<meta name=\"googlebot\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta name=\"bingbot\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/chezyueyin.org\/blog\/herland\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Herland -\" \/>\n<meta property=\"og:description\" content=\"Au tout d\u00e9but du XXe si\u00e8cle, un trio de jeunes am\u00e9ricains aventureux se lancent \u00e0 la recherche d&#8217;un myst\u00e9rieux pays peupl\u00e9s uniquement de femmes. Chacun port\u00e9 par ses fantasmes, ils ont imagin\u00e9 toutes les formes que pourraient prendre une telle &hellip; Continuer la lecture &rarr;\" \/>\n<meta property=\"og:url\" content=\"http:\/\/chezyueyin.org\/blog\/herland\/\" \/>\n<meta property=\"article:published_time\" content=\"1970-01-01T00:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2014-08-27T22:18:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/encrypted-tbn1.gstatic.com\/images?q=tbn:ANd9GcSBCtUU8NDGLWjvWr7KWddg6hxT-nOw_hckmP9SxnUxpC7IQCJOBg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"http:\/\/chezyueyin.org\/blog\/#website\",\"url\":\"http:\/\/chezyueyin.org\/blog\/\",\"name\":\"\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"http:\/\/chezyueyin.org\/blog\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"ImageObject\",\"@id\":\"http:\/\/chezyueyin.org\/blog\/herland\/#primaryimage\",\"inLanguage\":\"fr-FR\",\"url\":\"https:\/\/encrypted-tbn1.gstatic.com\/images?q=tbn:ANd9GcSBCtUU8NDGLWjvWr7KWddg6hxT-nOw_hckmP9SxnUxpC7IQCJOBg\"},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/chezyueyin.org\/blog\/herland\/#webpage\",\"url\":\"http:\/\/chezyueyin.org\/blog\/herland\/\",\"name\":\"Herland -\",\"isPartOf\":{\"@id\":\"http:\/\/chezyueyin.org\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\/\/chezyueyin.org\/blog\/herland\/#primaryimage\"},\"datePublished\":\"1970-01-01T00:00:00+00:00\",\"dateModified\":\"2014-08-27T22:18:58+00:00\",\"author\":{\"@id\":\"http:\/\/chezyueyin.org\/blog\/#\/schema\/person\/1a9310c3e663df5ecfc72321e080472a\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/chezyueyin.org\/blog\/herland\/\"]}]},{\"@type\":[\"Person\"],\"@id\":\"http:\/\/chezyueyin.org\/blog\/#\/schema\/person\/1a9310c3e663df5ecfc72321e080472a\",\"name\":\"yueyin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"http:\/\/chezyueyin.org\/blog\/#personlogo\",\"inLanguage\":\"fr-FR\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/1e806c47d6639b28584ec4f62fd12a1e07e1042510b36ac97a823d02fd787a70?s=96&d=mm&r=g\",\"caption\":\"yueyin\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"http:\/\/chezyueyin.org\/blog\/wp-json\/wp\/v2\/posts\/2603","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/chezyueyin.org\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/chezyueyin.org\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/chezyueyin.org\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/chezyueyin.org\/blog\/wp-json\/wp\/v2\/comments?post=2603"}],"version-history":[{"count":1,"href":"http:\/\/chezyueyin.org\/blog\/wp-json\/wp\/v2\/posts\/2603\/revisions"}],"predecessor-version":[{"id":2636,"href":"http:\/\/chezyueyin.org\/blog\/wp-json\/wp\/v2\/posts\/2603\/revisions\/2636"}],"wp:attachment":[{"href":"http:\/\/chezyueyin.org\/blog\/wp-json\/wp\/v2\/media?parent=2603"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/chezyueyin.org\/blog\/wp-json\/wp\/v2\/categories?post=2603"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/chezyueyin.org\/blog\/wp-json\/wp\/v2\/tags?post=2603"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}